{"id":74,"count":3,"description":"","link":"https:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/","name":"Hunnewell","slug":"hunnewell","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hunnewell Archives &#8212; Copper Country Architects<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hunnewell Archives &#8212; Copper Country Architects\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/\" \/>\n<meta property=\"og:site_name\" content=\"Copper Country Architects\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/tag\\\/hunnewell\\\/\",\"url\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/tag\\\/hunnewell\\\/\",\"name\":\"Hunnewell Archives &#8212; Copper Country Architects\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/tag\\\/hunnewell\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/tag\\\/hunnewell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hunnewell\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#website\",\"url\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/\",\"name\":\"Copper Country Architects\",\"description\":\"Biographical Dictionary of Copper Country Architects\",\"publisher\":{\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#organization\",\"name\":\"Michigan Tech Social Sciences Deparment\",\"url\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Social_Sciences_Color_Vertical.png\",\"contentUrl\":\"https:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Social_Sciences_Color_Vertical.png\",\"width\":614,\"height\":656,\"caption\":\"Michigan Tech Social Sciences Deparment\"},\"image\":{\"@id\":\"http:\\\/\\\/ss.sites.mtu.edu\\\/cca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hunnewell Archives &#8212; Copper Country Architects","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/","og_locale":"en_US","og_type":"article","og_title":"Hunnewell Archives &#8212; Copper Country Architects","og_url":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/","og_site_name":"Copper Country Architects","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/","url":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/","name":"Hunnewell Archives &#8212; Copper Country Architects","isPartOf":{"@id":"http:\/\/ss.sites.mtu.edu\/cca\/#website"},"breadcrumb":{"@id":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/ss.sites.mtu.edu\/cca\/tag\/hunnewell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ss.sites.mtu.edu\/cca\/"},{"@type":"ListItem","position":2,"name":"Hunnewell"}]},{"@type":"WebSite","@id":"http:\/\/ss.sites.mtu.edu\/cca\/#website","url":"http:\/\/ss.sites.mtu.edu\/cca\/","name":"Copper Country Architects","description":"Biographical Dictionary of Copper Country Architects","publisher":{"@id":"http:\/\/ss.sites.mtu.edu\/cca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ss.sites.mtu.edu\/cca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/ss.sites.mtu.edu\/cca\/#organization","name":"Michigan Tech Social Sciences Deparment","url":"http:\/\/ss.sites.mtu.edu\/cca\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/ss.sites.mtu.edu\/cca\/#\/schema\/logo\/image\/","url":"https:\/\/ss.sites.mtu.edu\/cca\/wp-content\/uploads\/2018\/12\/Social_Sciences_Color_Vertical.png","contentUrl":"https:\/\/ss.sites.mtu.edu\/cca\/wp-content\/uploads\/2018\/12\/Social_Sciences_Color_Vertical.png","width":614,"height":656,"caption":"Michigan Tech Social Sciences Deparment"},"image":{"@id":"http:\/\/ss.sites.mtu.edu\/cca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ss.sites.mtu.edu\/cca\/wp-json\/wp\/v2\/tags\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ss.sites.mtu.edu\/cca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ss.sites.mtu.edu\/cca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ss.sites.mtu.edu\/cca\/wp-json\/wp\/v2\/posts?tags=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}