{"id":8444,"date":"2018-01-04T12:10:20","date_gmt":"2018-01-04T17:10:20","guid":{"rendered":"http:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3.jpg"},"modified":"2019-11-02T17:33:15","modified_gmt":"2019-11-02T21:33:15","slug":"mhugl-header3","status":"inherit","type":"attachment","link":"https:\/\/ss.sites.mtu.edu\/mhugl\/mhugl-header3\/","title":{"rendered":"MHUGL header3"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-8444","attachment","type-attachment","status-inherit","hentry","entry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"31\" src=\"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-300x31.jpg\" class=\"attachment-medium size-medium\" alt=\"MHUGL header\" srcset=\"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-300x31.jpg 300w, https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-1024x105.jpg 1024w, https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3.jpg 1149w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>MHUGL header3<\/p>\n"},"caption":{"rendered":"<p>MHUGL header3<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/ss.sites.mtu.edu\/mhugl\/mhugl-header3\/\">Continue reading<span class=\"screen-reader-text\">MHUGL header3<\/span><\/a><\/div>\n"},"alt_text":"MHUGL header","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1149,"height":118,"file":"2018\/01\/MHUGL-header3.jpg","sizes":{"thumbnail":{"file":"MHUGL-header3-150x118.jpg","width":150,"height":118,"mime_type":"image\/jpeg","source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-150x118.jpg"},"medium":{"file":"MHUGL-header3-300x31.jpg","width":300,"height":31,"mime_type":"image\/jpeg","source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-300x31.jpg"},"large":{"file":"MHUGL-header3-1024x105.jpg","width":1024,"height":105,"mime_type":"image\/jpeg","source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-1024x105.jpg"},"popup-image":{"file":"MHUGL-header3-545x118.jpg","width":545,"height":118,"mime_type":"image\/jpeg","source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3-545x118.jpg"},"full":{"file":"MHUGL-header3.jpg","width":1149,"height":118,"mime_type":"image\/jpeg","source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-content\/uploads\/2018\/01\/MHUGL-header3.jpg","_links":{"self":[{"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/media\/8444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/comments?post=8444"}]}}