{"id":1,"name":"Steven Walton","url":"http:\/\/www.social.mtu.edu\/~sawalton","description":"","link":"https:\/\/ss.sites.mtu.edu\/mhugl\/author\/sawalton\/","slug":"sawalton","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a18d8caf17f5a6faa56e8486de2da75ab498dcb90536083ce7c9deebbedb956c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a18d8caf17f5a6faa56e8486de2da75ab498dcb90536083ce7c9deebbedb956c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a18d8caf17f5a6faa56e8486de2da75ab498dcb90536083ce7c9deebbedb956c?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ss.sites.mtu.edu\/mhugl\/wp-json\/wp\/v2\/users"}]}}